{"id":20618,"date":"2023-12-29T11:47:33","date_gmt":"2023-12-29T10:47:33","guid":{"rendered":"https:\/\/consorcioserrano.es\/?page_id=20618"},"modified":"2024-02-20T15:02:42","modified_gmt":"2024-02-20T14:02:42","slug":"elaborazione","status":"publish","type":"page","link":"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/elaborazione\/","title":{"rendered":"Elaborazione"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1698666272764{background-color: #161616 !important;}&#8221; el_class=&#8221;next-row-no-padding&#8221;][vc_column el_class=&#8221;column-no-padding&#8221;][vc_column_text css=&#8221;.vc_custom_1700569439245{padding-left: 100px !important;background-color: #161616 !important;}&#8221; el_class=&#8221;no-margin-with-padding no-margin-with-padding-left&#8221; el_id=&#8221;div-sello&#8221;]<\/p>\n<p class=\"image-h2\" style=\"padding-top: 0px; margin-bottom: 0px;\"><img decoding=\"async\" class=\"size-full wp-image-975 alignleft img-certificado-consorcio\" title=\"Certificado por Consorcio Serrano - Selecci\u00f3n a mano\" src=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2023\/11\/sello_jamon_consorcio_2023_red.png\" alt=\"Certificado por Consorcio Serrano - Selecci\u00f3n a mano\" width=\"140\" height=\"60\" fetchpriority=\"high\" \/><\/p>\n<h1 style=\"text-align: left;\"><strong>Prosciutto<\/strong> Consorcio Serrano<\/h1>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1703173685883{background-color: #000000 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_class=&#8221;no-padding-top six-columns consorcio-submenu&#8221;][vc_column][vc_wp_custommenu nav_menu=&#8221;11700&#8243; el_id=&#8221;consorcio-jamon-serrano&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1703241586360{background-color: #161616 !important;}&#8221; el_class=&#8221;no-padding-top six-columns consorcio-submenu&#8221; el_id=&#8221;consorcio-submenu&#8221;][vc_column width=&#8221;1\/6&#8243; offset=&#8221;vc_col-lg-2 vc_col-md-4 vc_hidden-sm vc_hidden-xs&#8221; el_class=&#8221;no-lateral-padding&#8221;]\n    <a href=\"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/storia-e-tradizione\/\"   class=\"vc_link_consorcio\" title=\" Storia e tradizione \">\n    <div class=\"roll_wrap\" id=\"\">\n\t\t\n        <div class=\"roll_wrap_img opacity-submenu-hover\" ><img decoding=\"async\" src=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/Historia-y-tradicion.jpg\" class=\"img-responsive \"  loading=\"lazy\" fetchpriority=\"low\"> <\/div>\n\t\t\n\n\t\t\n\t\t\n\t        <div class=\"roll_wrap_link_imagetextmenu  \" style=\"color:#ff0000; font-size:;\"><p class=\"six-columns-img\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2600 alignleft\" src=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/s-60.png\" alt=\"\" width=\"60\" height=\"60\" fetchpriority=\"low\" \/><\/p>\n<h3><strong>Storia<\/strong> e tradizione<\/h3>\n<\/div>\n\t\t\n    <\/div>\n    <\/a>[\/vc_column][vc_column width=&#8221;1\/6&#8243; offset=&#8221;vc_col-lg-2 vc_col-md-4 vc_hidden-sm vc_hidden-xs&#8221; el_class=&#8221;no-lateral-padding&#8221;]\n    <a href=\"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/elaborazione\/\"   class=\"vc_link_consorcio\" title=\" Elaborazione \">\n    <div class=\"roll_wrap\" id=\"\">\n\t\t\n        <div class=\"roll_wrap_img \" ><img decoding=\"async\" src=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/Elaboracion.jpg\" class=\"img-responsive \"  loading=\"lazy\" fetchpriority=\"low\"> <\/div>\n\t\t\n\n\t\t\n\t\t\n\t        <div class=\"roll_wrap_link_imagetextmenu  \" style=\"color:#ff0000; font-size:;\"><p class=\"six-columns-img\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2600 alignleft\" src=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/s-60.png\" alt=\"\" width=\"60\" height=\"60\" fetchpriority=\"low\" \/><\/p>\n<h3><strong>Elaborazione<\/strong><\/h3>\n<\/div>\n\t\t\n    <\/div>\n    <\/a>[\/vc_column][vc_column width=&#8221;1\/6&#8243; offset=&#8221;vc_col-lg-2 vc_col-md-4 vc_hidden-sm vc_hidden-xs&#8221; el_class=&#8221;no-lateral-padding&#8221;]\n    <a href=\"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/sapore-aroma-e-conservazione\/\"   class=\"vc_link_consorcio\" title=\" Sapore\/aroma e conservazione \">\n    <div class=\"roll_wrap\" id=\"\">\n\t\t\n        <div class=\"roll_wrap_img opacity-submenu-hover\" ><img decoding=\"async\" src=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/Sabor-y-aroma.jpg\" class=\"img-responsive \"  loading=\"lazy\" fetchpriority=\"low\"> <\/div>\n\t\t\n\n\t\t\n\t\t\n\t        <div class=\"roll_wrap_link_imagetextmenu  \" style=\"color:#ff0000; font-size:;\"><p class=\"six-columns-img\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2600 alignleft\" src=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/s-60.png\" alt=\"\" width=\"60\" height=\"60\" fetchpriority=\"low\" \/><\/p>\n<h3><strong>Sapore\/aroma<\/strong> e conservazione<\/h3>\n<\/div>\n\t\t\n    <\/div>\n    <\/a>[\/vc_column][vc_column width=&#8221;1\/6&#8243; offset=&#8221;vc_col-lg-2 vc_col-md-4 vc_hidden-sm vc_hidden-xs&#8221; el_class=&#8221;no-lateral-padding&#8221;]\n    <a href=\"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/garanzia-di-qualita\/\"   class=\"vc_link_consorcio\" title=\" Garanzia di qualit\u00e0 \">\n    <div class=\"roll_wrap\" id=\"\">\n\t\t\n        <div class=\"roll_wrap_img opacity-submenu-hover\" ><img decoding=\"async\" src=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/Garantia-de-calidad.jpg\" class=\"img-responsive \"  loading=\"lazy\" fetchpriority=\"low\"> <\/div>\n\t\t\n\n\t\t\n\t\t\n\t        <div class=\"roll_wrap_link_imagetextmenu  \" style=\"color:#ff0000; font-size:;\"><p class=\"six-columns-img\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2600 alignleft\" src=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/s-60.png\" alt=\"\" width=\"60\" height=\"60\" fetchpriority=\"low\" \/><\/p>\n<h3><strong>Garanzia<\/strong> di qualit\u00e0<\/h3>\n<\/div>\n\t\t\n    <\/div>\n    <\/a>[\/vc_column][vc_column width=&#8221;1\/6&#8243; offset=&#8221;vc_col-lg-2 vc_col-md-4 vc_hidden-sm vc_hidden-xs&#8221; el_class=&#8221;no-lateral-padding&#8221;]\n    <a href=\"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/come-consumarlo\/\"   class=\"vc_link_consorcio\" title=\" Come consumarlo \">\n    <div class=\"roll_wrap\" id=\"\">\n\t\t\n        <div class=\"roll_wrap_img opacity-submenu-hover\" ><img decoding=\"async\" src=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/Como-consumirlo.jpg\" class=\"img-responsive \"  loading=\"lazy\" fetchpriority=\"low\"> <\/div>\n\t\t\n\n\t\t\n\t\t\n\t        <div class=\"roll_wrap_link_imagetextmenu  \" style=\"color:#ff0000; font-size:;\"><p class=\"six-columns-img\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2600 alignleft\" src=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/s-60.png\" alt=\"\" width=\"60\" height=\"60\" fetchpriority=\"low\" \/><\/p>\n<h3>Come <strong>consumarlo<\/strong><\/h3>\n<\/div>\n\t\t\n    <\/div>\n    <\/a>[\/vc_column][vc_column width=&#8221;1\/6&#8243; offset=&#8221;vc_col-lg-2 vc_col-md-4 vc_hidden-sm vc_hidden-xs&#8221; el_class=&#8221;no-lateral-padding&#8221;]\n    <a href=\"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/tipi-di-prosciutto\/\"   class=\"vc_link_consorcio\" title=\" Tipi di prosciutto \">\n    <div class=\"roll_wrap\" id=\"\">\n\t\t\n        <div class=\"roll_wrap_img opacity-submenu-hover\" ><img decoding=\"async\" src=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/Tipos-de-Jamon.jpg\" class=\"img-responsive \"  loading=\"lazy\" fetchpriority=\"low\"> <\/div>\n\t\t\n\n\t\t\n\t\t\n\t        <div class=\"roll_wrap_link_imagetextmenu  \" style=\"color:#ff0000; font-size:;\"><p class=\"six-columns-img\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2600 alignleft\" src=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/s-60.png\" alt=\"\" width=\"60\" height=\"60\" fetchpriority=\"low\" \/><\/p>\n<h3><strong>Tipi<\/strong> di prosciutto<\/h3>\n<\/div>\n\t\t\n    <\/div>\n    <\/a>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1509714725485{background-image: url(https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/elaboracion-header-1900-1.jpg?id=2015) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column]\n<div id=\"ersspace-1\"><\/div><style type=\"text\/css\">#ersspace-1 { height: 320px; }\n@media handheld, only screen and (max-width: 1199px) {\n\t#ersspace-1 { height: 300px; }\n}\n@media handheld, only screen and (max-width: 1023px) {\n\t#ersspace-1 { height: 300px; }\n}\n@media handheld, only screen and (max-width: 767px) {\n\t#ersspace-1 { height: 260px; }\n}<\/style>[\/vc_column][\/vc_row][vc_row el_class=&#8221;column-special-one&#8221;][vc_column width=&#8221;2\/3&#8243; el_class=&#8221;panel-special-content&#8221;][vc_row_inner][vc_column_inner][vc_column_text el_class=&#8221;vc_quote_consorcio&#8221;]<\/p>\n<div class=\"vc_quote_consorcio_icon\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1101\" src=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/comillas-abrir-1.png\" alt=\"\" width=\"59\" height=\"53\" srcset=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/comillas-abrir-1.png 59w, https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/comillas-abrir-1-50x45.png 50w\" sizes=\"auto, (max-width:767px) 59px, 59px\" fetchpriority=\"low\" \/><\/div>\n<div class=\"vc_quote_consorcio_content\">\n<h1><strong>Elaborazione<\/strong> del<br \/>\nprosciutto consorcio serrano<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1100\" src=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/comillas-cerrar-1.png\" alt=\"\" width=\"59\" height=\"53\" srcset=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/comillas-cerrar-1.png 59w, https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/comillas-cerrar-1-50x45.png 50w\" sizes=\"auto, (max-width:767px) 59px, 59px\" fetchpriority=\"low\" \/><\/h1>\n<\/div>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h3><span style=\"color: #e82f37;\">Elaborazione<\/span><\/h3>\n<p>L&#8217;elaborazione del prosciutto serrano del <strong>Consorcio Serrano Espa\u00f1ol<\/strong> richiede, soprattutto, una materia prima di qualit\u00e0. Tale materia prima \u00e8 garantita dall&#8217;accurata politica di acquisti dei suoi soci, oltre alla rigorosa osservanza della normativa sul prodotto definita <strong>nelle norme di qualit\u00e0 del Consorcio<\/strong>.<\/p>\n<h4><span style=\"color: #e82f37;\">Selezione manuale<\/span><\/h4>\n<p>Questa normativa prevede una materia prima con un maggior spessore di grasso nella zona pi\u00f9 critica, e dei livelli di grasso nell&#8217;intero pezzo che la rendono pi\u00f9 adatta al livello di stagionatura c<strong>he il prosciutto serrano Consorcio Serrano richiede.<\/strong> Tutto ci\u00f2 viene completato con un controllo visivo pezzo per pezzo di prosciutto serrano<strong>, <\/strong>poich\u00e9 solo si selezionano i pezzi migliori quando un esperto prosciuttaio <strong>li esamina e li seleziona a mano, <\/strong>eliminando quelli prosciutto crudo con difetti critici e quindi non adatti alla lavorazione.[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h4><\/h4>\n<h4><\/h4>\n<p>&nbsp;<\/p>\n<h4><span class=\"HwtZe\" lang=\"it\" style=\"color: #e82f37;\"><span class=\"jCAhz ChMk0b\"><span class=\"ryNqvb\">Processo di autentico prosciutto serrano spagnolo<\/span><\/span><\/span><\/h4>\n<ul>\n<li>Il Prosciutto fresco (materia prima) che sar\u00e0 utilizzato per l&#8217;elaborazione del <strong>Prosciutto Consorcio Serrano<\/strong>, si classifica per peso e per contenuto di grasso negli stabilimenti di produzione delle industrie dei nostri soci.<\/li>\n<li>Da l\u00ec i prosciutti vengono portati a temperatura ambiente prima di essere introdotti nel sale. Ci\u00f2 implica che il prosciutto crudo non deve avere una temperatura superiore ai 5\u00baC nel momento in cui entra in contatto con tale elemento.<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner][vc_video link=&#8221;https:\/\/youtu.be\/4PtAH9qKysA&#8221; align=&#8221;center&#8221;][vc_column_text]<a href=\"https:\/\/consorcioserrano.es\/videos\/es\/elaboracion-jamon-consorcio-serrano.mp4\" target=\"_blank\" rel=\"noopener noreferrer\" download=\"\">Scarica il video di &#8220;Elaborazione del prosciutto consorcio serrano&#8221;.<\/a>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_column_text el_class=&#8221;vc_quote_consorcio vc_quote_consorcio_other&#8221;]<\/p>\n<div class=\"vc_quote_consorcio_icon\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1101\" src=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/comillas-abrir-1.png\" alt=\"\" width=\"59\" height=\"53\" srcset=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/comillas-abrir-1.png 59w, https:\/\/consorcioserrano.es\/wp-content\/uploads\/2017\/10\/comillas-abrir-1-50x45.png 50w\" sizes=\"auto, (max-width:767px) 59px, 59px\" fetchpriority=\"low\" \/><\/div>\n<div class=\"vc_quote_consorcio_content\">\n<h2><span class=\"HwtZe\" lang=\"it\"><span class=\"jCAhz ChMk0b C1N51c\"><span class=\"ryNqvb\">Una materia prima con uno spessore di grasso maggiore nella zona pi\u00f9 critica, e livelli di grasso nell&#8217;intero prosciutto serrano che lo rendono pi\u00f9 adatto <strong>al livello di stagionatura che il Consorzio Serrano richiede.<\/strong><\/span><\/span><\/span><\/h2>\n<\/div>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]Il controllo di questa prima fase di <strong>stabilizzazione microbiologica<\/strong> del prosciutto serrano fresco mediante basse temperature ed alta umidit\u00e0, \u00e8 la cosa pi\u00f9 importante per ottenere un&#8217;ottima elaborazione del prodotto nelle fasi successive dell&#8217;elaborazione. A questa fase seguono:<\/p>\n<ul>\n<li><strong>Salatura e post-salatura<\/strong>: questa fase \u00e8 caratterizzata dall&#8217;incorporazione di sale marino al prodotto fresco, favorendo la disidratazione e la conservazione dei prosciutti serrano interi.<\/li>\n<li><strong>Asciugatura e stagionatura<\/strong>: in questa fase si eleva progressivamente la temperatura e si riduce l&#8217;umidit\u00e0. Ci\u00f2 provoca una fusione naturale di una parte dei grassi della sua protezione adiposa, ottenendo una distribuzione uniforme dei grassi nel tessuto muscolare. \u00c8 cos\u00ec che si ottengono le caratteristiche sensoriali, colore, aroma e sapore, tipiche del prosciutto serrano spagnolo.<\/li>\n<li><strong>Invecchiamento in cantina<\/strong>: \u00e8 la fase finale del processo di stagionatura del prosciutto serrano, dove questo finisce di maturare in modo molto lento, fino a convertirsi nel prodotto gourmet che \u00e8.<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<ul>\n<li><strong>Selezione<\/strong>: quando il prosciutto serrano \u00e8 pronto per la sua commercializzazione, un team di ispettori del Consorcio del Jam\u00f3n Serrano Espa\u00f1ol seleziona uno a uno quei prosciutti che, per il loro aspetto e caratteristiche organolettiche, riuniscono tutti i requisiti stabiliti nella nostra normativa sulla qualit\u00e0.<\/li>\n<li><strong>Marchiatura<\/strong>: tutti i prosciutti serrano che hanno superato con successo i processi di selezione sono marchiati e identificati con il Marchio di Qualit\u00e0 Consorcio Serrano. Questo marchio garantisce al consumatore la fruizione di un prodotto di ottima qualit\u00e0: la qualit\u00e0 di <strong>un prosciutto serrano tradizionale, selezionato a mano, <\/strong>e questa sar\u00e0 la sua lettera di presentazione all&#8217;estero.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Alla fine del processo di elaborazione, che normalmente dura tra un anno e un anno e mezzo, avremmo ottenuto un Prosciutto Crudo Consorcio Serrano con delle eccezionali caratteristiche organolettiche e sensoriali, inconfondibile per il suo colore, il suo aroma, il suo aspetto e la sua consistenza.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/3&#8243;]\n<div id=\"ersspace-2\"><\/div><style type=\"text\/css\">#ersspace-2 { height: 260px; }\n@media handheld, only screen and (max-width: 767px) {\n\t#ersspace-2 { height: 0px; }\n}<\/style>[vc_row_inner el_class=&#8221;panel-special-aside&#8221;][vc_column_inner][vc_column_text]<\/p>\n<h3><span style=\"color: #e82f37;\">Elaborazione Consorcio Jam\u00f3n Serrano Espa\u00f1ol<\/span><\/h3>\n<p>Il Consorcio realizza audit annuali negli stabilimenti di produzione aderenti per vigilare e controllare l&#8217;intero processo di elaborazione. In generale, il processo di elaborazione del Prosciutto Consorcio Serrano \u00e8 determinato da una serie di parametri:<br \/>\n[\/vc_column_text][vc_single_image image=&#8221;1599&#8243; img_size=&#8221;full&#8221;][vc_column_text]<\/p>\n<ul>\n<li><strong>Perdite<\/strong>: i prosciutti elaborati secondo le direttive del Consorcio hanno una perdita di umidit\u00e0 a seconda del loro peso fresco che supera il 34%. Ci\u00f2 ci assicura un insieme di qualit\u00e0 nel prosciutto crudo serrano tra cui risalta la consistenza.<\/li>\n<li><strong>Tempo di stagionatura<\/strong>: un minimo di 12 mesi, a partire da quando il pezzo \u00e8 stato introdotto nel sale.<\/li>\n<li><strong>Contenuto di grasso<\/strong>: Molto importante per lo sviluppo delle caratteristiche sensoriali del prosciutto serrano e per ottenere un&#8217;ottima stagionatura nei prosciutti di qualit\u00e0.<\/li>\n<li><strong>Selezione a mano,<\/strong> uno per uno, dei migliori pezzi dei migliori produttori di prosciutto serrano spagnolo.<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_single_image image=&#8221;22553&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; onclick=&#8221;link_image&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column]\n<div id=\"ersspace-3\"><\/div><style type=\"text\/css\">#ersspace-3 { height: 80px; }<\/style>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1698666272764{background-color: #161616 !important;}&#8221; el_class=&#8221;next-row-no-padding&#8221;][vc_column el_class=&#8221;column-no-padding&#8221;][vc_column_text css=&#8221;.vc_custom_1700569439245{padding-left: 100px !important;background-color: #161616 !important;}&#8221; el_class=&#8221;no-margin-with-padding no-margin-with-padding-left&#8221; el_id=&#8221;div-sello&#8221;] Prosciutto Consorcio Serrano [\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1703173685883{background-color: #000000 !important;background-position: center !important;background-repeat: no-repeat<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":7563,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-20618","page","type-page","status-publish","hentry","sections_group lang-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elaborazione - Consorcio Prosciutto Serrano<\/title>\n<meta name=\"description\" content=\"Il Prosciutto Serrano e il processo produttivo del Consorcio Serrano. Stagionatura, tradizione e selezione manuale del miglior prosciutti serrano spagnoli\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/elaborazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elaborazione - Consorcio Prosciutto Serrano\" \/>\n<meta property=\"og:description\" content=\"Il Prosciutto Serrano e il processo produttivo del Consorcio Serrano. Stagionatura, tradizione e selezione manuale del miglior prosciutti serrano spagnoli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/elaborazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Consorcio del Jam\u00f3n Serrano Espa\u00f1ol\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-20T14:02:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2023\/11\/sello_jamon_consorcio_2023_red.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/prosciutto-consorcio-serrano\\\/elaborazione\\\/\",\"url\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/prosciutto-consorcio-serrano\\\/elaborazione\\\/\",\"name\":\"Elaborazione - Consorcio Prosciutto Serrano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/prosciutto-consorcio-serrano\\\/elaborazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/prosciutto-consorcio-serrano\\\/elaborazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/consorcioserrano.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/sello_jamon_consorcio_2023_red.png\",\"datePublished\":\"2023-12-29T10:47:33+00:00\",\"dateModified\":\"2024-02-20T14:02:42+00:00\",\"description\":\"Il Prosciutto Serrano e il processo produttivo del Consorcio Serrano. Stagionatura, tradizione e selezione manuale del miglior prosciutti serrano spagnoli\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/prosciutto-consorcio-serrano\\\/elaborazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/prosciutto-consorcio-serrano\\\/elaborazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/prosciutto-consorcio-serrano\\\/elaborazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/consorcioserrano.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/sello_jamon_consorcio_2023_red.png\",\"contentUrl\":\"https:\\\/\\\/consorcioserrano.es\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/sello_jamon_consorcio_2023_red.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/prosciutto-consorcio-serrano\\\/elaborazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prosciutto Consorcio Serrano\",\"item\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/prosciutto-consorcio-serrano\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Elaborazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/#website\",\"url\":\"https:\\\/\\\/consorcioserrano.es\\\/\",\"name\":\"Consorcio del Jam\u00f3n Serrano Espa\u00f1ol\",\"description\":\"Consorcio Prosciutto Serrano Spagnolo: garanzia del miglior Prosciutto Serrano - 100% prosciutti spagnoli - Prosciutto crudo spagnolo selezionato a mano\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/consorcioserrano.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elaborazione - Consorcio Prosciutto Serrano","description":"Il Prosciutto Serrano e il processo produttivo del Consorcio Serrano. Stagionatura, tradizione e selezione manuale del miglior prosciutti serrano spagnoli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/elaborazione\/","og_locale":"it_IT","og_type":"article","og_title":"Elaborazione - Consorcio Prosciutto Serrano","og_description":"Il Prosciutto Serrano e il processo produttivo del Consorcio Serrano. Stagionatura, tradizione e selezione manuale del miglior prosciutti serrano spagnoli","og_url":"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/elaborazione\/","og_site_name":"Consorcio del Jam\u00f3n Serrano Espa\u00f1ol","article_modified_time":"2024-02-20T14:02:42+00:00","og_image":[{"url":"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2023\/11\/sello_jamon_consorcio_2023_red.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/elaborazione\/","url":"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/elaborazione\/","name":"Elaborazione - Consorcio Prosciutto Serrano","isPartOf":{"@id":"https:\/\/consorcioserrano.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/elaborazione\/#primaryimage"},"image":{"@id":"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/elaborazione\/#primaryimage"},"thumbnailUrl":"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2023\/11\/sello_jamon_consorcio_2023_red.png","datePublished":"2023-12-29T10:47:33+00:00","dateModified":"2024-02-20T14:02:42+00:00","description":"Il Prosciutto Serrano e il processo produttivo del Consorcio Serrano. Stagionatura, tradizione e selezione manuale del miglior prosciutti serrano spagnoli","breadcrumb":{"@id":"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/elaborazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/elaborazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/elaborazione\/#primaryimage","url":"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2023\/11\/sello_jamon_consorcio_2023_red.png","contentUrl":"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2023\/11\/sello_jamon_consorcio_2023_red.png"},{"@type":"BreadcrumbList","@id":"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/elaborazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/consorcioserrano.es\/it\/inicio\/"},{"@type":"ListItem","position":2,"name":"Prosciutto Consorcio Serrano","item":"https:\/\/consorcioserrano.es\/it\/prosciutto-consorcio-serrano\/"},{"@type":"ListItem","position":3,"name":"Elaborazione"}]},{"@type":"WebSite","@id":"https:\/\/consorcioserrano.es\/#website","url":"https:\/\/consorcioserrano.es\/","name":"Consorcio del Jam\u00f3n Serrano Espa\u00f1ol","description":"Consorcio Prosciutto Serrano Spagnolo: garanzia del miglior Prosciutto Serrano - 100% prosciutti spagnoli - Prosciutto crudo spagnolo selezionato a mano","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/consorcioserrano.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/pages\/20618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/comments?post=20618"}],"version-history":[{"count":4,"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/pages\/20618\/revisions"}],"predecessor-version":[{"id":22903,"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/pages\/20618\/revisions\/22903"}],"up":[{"embeddable":true,"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/pages\/7563"}],"wp:attachment":[{"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/media?parent=20618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}