{"id":14573,"date":"2021-12-21T13:33:13","date_gmt":"2021-12-21T12:33:13","guid":{"rendered":"https:\/\/consorcioserrano.es\/?p=14573"},"modified":"2021-12-21T13:33:13","modified_gmt":"2021-12-21T12:33:13","slug":"le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021","status":"publish","type":"post","link":"https:\/\/consorcioserrano.es\/it\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\/","title":{"rendered":"Le esportazioni di prosciutto e prosciuttini stagionati crescono del 14,17% fino al terzo trimestre del 2021"},"content":{"rendered":"<p><strong><em><img decoding=\"async\" class=\" wp-image-14502 aligncenter\" src=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2021\/12\/camion_contenedores.jpg\" alt=\"Exportacion Jam\u00f3n Serrano\" width=\"541\" height=\"359\" srcset=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2021\/12\/camion_contenedores.jpg 612w, https:\/\/consorcioserrano.es\/wp-content\/uploads\/2021\/12\/camion_contenedores-300x199.jpg 300w, https:\/\/consorcioserrano.es\/wp-content\/uploads\/2021\/12\/camion_contenedores-220x146.jpg 220w, https:\/\/consorcioserrano.es\/wp-content\/uploads\/2021\/12\/camion_contenedores-50x33.jpg 50w, https:\/\/consorcioserrano.es\/wp-content\/uploads\/2021\/12\/camion_contenedores-113x75.jpg 113w\" sizes=\"auto, (max-width:767px) 480px, 541px\" fetchpriority=\"high\" \/><\/em><\/strong><\/p>\n<p><strong><em>&gt;&gt; Durante i primi nove mesi dell&#8217;anno, le esportazioni hanno raggiunto 36.644,81 tonnellate rispetto alle 32.097,93 tonnellate dello stesso periodo del 2020<\/em><\/strong><\/p>\n<p><strong><em>&gt;&gt; A incarnare la crescita pi\u00f9 notevole in termini di valore sono stati Cile, Cina e Stati Uniti<\/em><\/strong><\/p>\n<p><strong><em>&gt;&gt; Durante questo periodo, i paesi terzi hanno guadagnato peso nelle esportazioni, rappresentando il 27,3%<\/em><\/strong><\/p>\n<p><strong><u>Madrid, 09 dicembre 2021<\/u><\/strong> &#8211; Il Consorcio del Jam\u00f3n Serrano Espa\u00f1ol (CJSE) ha reso noti i dati relativi alle esportazioni di prosciutti e prosciuttini stagionati spagnoli fino al terzo trimestre del 2021, periodo in cui sono state esportate complessivamente 36.644,81 tonnellate, rispetto alle 32.097,93 del periodo precedente, con un aumento del 14,17%. Allo stesso modo, sono state effettuate <strong>esportazioni per un valore totale di 364.059.845,82 euro<\/strong>, con un aumento del 15,58% rispetto all&#8217;anno precedente.<\/p>\n<p>Inoltre, il <strong>prezzo medio \u00e8 aumentato dell&#8217;1,24%<\/strong> durante questo periodo raggiungendo i 9,93 euro. Il prezzo medio nei paesi dell&#8217;Unione Europea \u00e8 stato di 9,01 euro, rispetto a 12,41 euro nei paesi terzi, con un leggero aggiustamento dello 0,18% e dello 0,20%, rispettivamente.<\/p>\n<p><em>\u201cLa ripresa dei consumi in quasi tutti i mercati strategici ha fatto s\u00ec che, nel corso dei primi nove mesi dell&#8217;anno, le esportazioni di prosciutto stagionato abbiano continuato a recuperare gradualmente, per tornare, in generale, ai livelli pre-Covid, potendo anzi superarli. Inoltre, durante questo periodo, abbiamo assistito a una crescita delle esportazioni da parte dei paesi terzi: il tradizionale rapporto di esportazione verso l&#8217;Unione Europea dell&#8217;80-20% \u00e8 arrivato a un\u2019inversione fino all&#8217;attuale 70-30%\u201d<\/em>, spiega Carlos del Hoyo, Direttore marketing e promozione del Consorcio del Jam\u00f3n Serrano Espa\u00f1ol.<\/p>\n<p>Quindi, a livello globale, i paesi dell&#8217;Unione Europea hanno importato un totale di 26.628,93 tonnellate durante questo periodo, mentre i paesi terzi hanno registrato un volume di 10.015,88 tonnellate. L&#8217;Unione Europea rappresenta il 72,7% delle esportazioni di prosciutto stagionato, mentre i paesi terzi rappresentano il 27,3%.<\/p>\n<p>All&#8217;interno dell&#8217;Unione Europea, le principali destinazioni del prosciutto Serrano continuano ad essere <strong>Francia e Germania<\/strong>, che hanno visto aumentare il loro valore del 10,59% e dello 0,07% e continuano a rappresentare pi\u00f9 del 50% delle esportazioni del prodotto, seguite da <strong>Portogallo e Italia<\/strong>. Nel frattempo, i mercati che hanno aumentato maggiormente il valore delle loro esportazioni durante la prima met\u00e0 del 2021 sono stati il <strong>Belgio, del 19,81%, l&#8217;Italia, del 14,99%, e i Paesi Bassi, del 14,35%<\/strong>. Vale anche la pena sottolineare il caso della Svezia, che rappresenta il mercato europeo con il prezzo medio pi\u00f9 alto, a 14,12 \u20ac\/kg.<\/p>\n<p>D&#8217;altra parte, i paesi terzi che hanno mostrato la crescita pi\u00f9 significativa in termini di valore sono stati <strong>il Cile, del 107,75%, e la Cina, del 103,45%<\/strong>. Il paese asiatico, inoltre, continua ad essere il mercato con il prezzo pi\u00f9 alto, a 16,64 \u20ac\/kg, nonostante la diminuzione del 17,26%. D&#8217;altra parte, il Regno Unito ha subito un calo dell&#8217;1,07%, anche se il suo prezzo medio \u00e8 aumentato dell&#8217;11,66% raggiungendo i 14,82 \u20ac\/kg; l&#8217;Australia, invece, ha aumentato il suo valore del 23,95% e il suo prezzo medio dell&#8217;1,82%.<\/p>\n<p>\u00c8 importante sottolineare il significativo aumento del 56,55% registrato negli <strong>Stati Uniti<\/strong>, nonostante un calo del 3,20% del prezzo medio. Da parte sua, Carlos del Hoyo spiega che <em>\u201cgli Stati Uniti sono diventati la principale destinazione del prosciutto Serrano al di fuori dell&#8217;Unione Europea e il CJSE prevede che diventer\u00e0 il terzo o quarto mercato pi\u00f9 importante.<\/em><em> D&#8217;altra parte, \u00e8 importante sottolineare l&#8217;aumento che continua a registrare la Cina, che raggiunger\u00e0 pi\u00f9 di 1.000 tonnellate, cos\u00ec come la crescita costante che sta avvenendo in altri mercati come il Messico e l&#8217;Australia. Di contro, il Regno Unito ha subito un calo dell&#8217;11,40% in volume e dell&#8217;1% in valore, a causa della carenza causata dalla Brexit e dall&#8217;incidenza e dalle restrizioni della pandemia\u201d. <\/em><\/p>\n<p>Per quanto riguarda i <strong>formati<\/strong>, il 19,10% dei pezzi esportati in questo periodo corrisponde al <strong>formato con osso<\/strong>, che ha contribuito a una crescita del 30,75% in termini di volume e del 36,37% in termini di valore. A questo proposito, il Direttore marketing e promozione del CJSE sottolinea che \u201cqueste cifre in aumento sono state dovute alla riapertura del settore alberghiero e della ristorazione e al fatto che questo formato rappresenta un&#8217;attrazione commerciale nella grande distribuzione per il periodo natalizio; il Cile e il Messico sono i paesi che hanno registrato la maggiore crescita in termini di prezzo medio di questo formato.<em> La Cina, da parte sua, \u00e8 il mercato che, in proporzione, sta importando pi\u00f9 prosciutto con osso\u201d.<\/em> Infine, il <strong>prosciutto disossato<\/strong> \u00e8 aumentato del 10,65% in volume e dell&#8217;11,66% in valore: qui, Cina e Regno Unito rappresentano i consumatori con i prezzi pi\u00f9 alti per questo formato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&gt;&gt; Durante i primi nove mesi dell&#8217;anno, le esportazioni hanno raggiunto 36.644,81 tonnellate rispetto alle 32.097,93 tonnellate dello stesso periodo del 2020 &gt;&gt; A incarnare la<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":1,"featured_media":14502,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11458,11459],"tags":[],"class_list":["post-14573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-stampa","category-sul-consorcio-serrano","sections_group lang-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le esportazioni di prosciutto e prosciuttini stagionati crescono del 14,17% fino al terzo trimestre del 2021 - Consorcio Prosciutto Serrano<\/title>\n<meta name=\"description\" content=\"Consorcio Prosciutto Serrano Spagnolo: garanzia del miglior Prosciutto Serrano - 100% prosciutti spagnoli - Prosciutto crudo spagnolo selezionato a mano\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/consorcioserrano.es\/it\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le esportazioni di prosciutto e prosciuttini stagionati crescono del 14,17% fino al terzo trimestre del 2021 - Consorcio Prosciutto Serrano\" \/>\n<meta property=\"og:description\" content=\"Consorcio Prosciutto Serrano Spagnolo: garanzia del miglior Prosciutto Serrano - 100% prosciutti spagnoli - Prosciutto crudo spagnolo selezionato a mano\" \/>\n<meta property=\"og:url\" content=\"https:\/\/consorcioserrano.es\/it\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Consorcio del Jam\u00f3n Serrano Espa\u00f1ol\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-21T12:33:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2021\/12\/camion_contenedores.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"612\" \/>\n\t<meta property=\"og:image:height\" content=\"406\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"eMutation\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"eMutation\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\\\/\"},\"author\":{\"name\":\"eMutation\",\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/#\\\/schema\\\/person\\\/349ec1d93548782b3ecf3331d50e0535\"},\"headline\":\"Le esportazioni di prosciutto e prosciuttini stagionati crescono del 14,17% fino al terzo trimestre del 2021\",\"datePublished\":\"2021-12-21T12:33:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\\\/\"},\"wordCount\":735,\"image\":{\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/consorcioserrano.es\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/camion_contenedores.jpg\",\"articleSection\":[\"Notizie e stampa\",\"Sul Consorcio Serrano\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\\\/\",\"url\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\\\/\",\"name\":\"Le esportazioni di prosciutto e prosciuttini stagionati crescono del 14,17% fino al terzo trimestre del 2021 - Consorcio Prosciutto Serrano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/consorcioserrano.es\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/camion_contenedores.jpg\",\"datePublished\":\"2021-12-21T12:33:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/#\\\/schema\\\/person\\\/349ec1d93548782b3ecf3331d50e0535\"},\"description\":\"Consorcio Prosciutto Serrano Spagnolo: garanzia del miglior Prosciutto Serrano - 100% prosciutti spagnoli - Prosciutto crudo spagnolo selezionato a mano\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/consorcioserrano.es\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/camion_contenedores.jpg\",\"contentUrl\":\"https:\\\/\\\/consorcioserrano.es\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/camion_contenedores.jpg\",\"width\":612,\"height\":406,\"caption\":\"Exportacion Jam\u00f3n Serrano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/consorcioserrano.es\\\/it\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le esportazioni di prosciutto e prosciuttini stagionati crescono del 14,17% fino al terzo trimestre del 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/#website\",\"url\":\"https:\\\/\\\/consorcioserrano.es\\\/\",\"name\":\"Consorcio del Jam\u00f3n Serrano Espa\u00f1ol\",\"description\":\"Consorcio Prosciutto Serrano Spagnolo: garanzia del miglior Prosciutto Serrano - 100% prosciutti spagnoli - Prosciutto crudo spagnolo selezionato a mano\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/consorcioserrano.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/consorcioserrano.es\\\/#\\\/schema\\\/person\\\/349ec1d93548782b3ecf3331d50e0535\",\"name\":\"eMutation\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le esportazioni di prosciutto e prosciuttini stagionati crescono del 14,17% fino al terzo trimestre del 2021 - Consorcio Prosciutto Serrano","description":"Consorcio Prosciutto Serrano Spagnolo: garanzia del miglior Prosciutto Serrano - 100% prosciutti spagnoli - Prosciutto crudo spagnolo selezionato a mano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/consorcioserrano.es\/it\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\/","og_locale":"it_IT","og_type":"article","og_title":"Le esportazioni di prosciutto e prosciuttini stagionati crescono del 14,17% fino al terzo trimestre del 2021 - Consorcio Prosciutto Serrano","og_description":"Consorcio Prosciutto Serrano Spagnolo: garanzia del miglior Prosciutto Serrano - 100% prosciutti spagnoli - Prosciutto crudo spagnolo selezionato a mano","og_url":"https:\/\/consorcioserrano.es\/it\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\/","og_site_name":"Consorcio del Jam\u00f3n Serrano Espa\u00f1ol","article_published_time":"2021-12-21T12:33:13+00:00","og_image":[{"width":612,"height":406,"url":"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2021\/12\/camion_contenedores.jpg","type":"image\/jpeg"}],"author":"eMutation","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"eMutation","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/consorcioserrano.es\/it\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\/#article","isPartOf":{"@id":"https:\/\/consorcioserrano.es\/it\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\/"},"author":{"name":"eMutation","@id":"https:\/\/consorcioserrano.es\/#\/schema\/person\/349ec1d93548782b3ecf3331d50e0535"},"headline":"Le esportazioni di prosciutto e prosciuttini stagionati crescono del 14,17% fino al terzo trimestre del 2021","datePublished":"2021-12-21T12:33:13+00:00","mainEntityOfPage":{"@id":"https:\/\/consorcioserrano.es\/it\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\/"},"wordCount":735,"image":{"@id":"https:\/\/consorcioserrano.es\/it\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2021\/12\/camion_contenedores.jpg","articleSection":["Notizie e stampa","Sul Consorcio Serrano"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/consorcioserrano.es\/it\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\/","url":"https:\/\/consorcioserrano.es\/it\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\/","name":"Le esportazioni di prosciutto e prosciuttini stagionati crescono del 14,17% fino al terzo trimestre del 2021 - Consorcio Prosciutto Serrano","isPartOf":{"@id":"https:\/\/consorcioserrano.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/consorcioserrano.es\/it\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\/#primaryimage"},"image":{"@id":"https:\/\/consorcioserrano.es\/it\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2021\/12\/camion_contenedores.jpg","datePublished":"2021-12-21T12:33:13+00:00","author":{"@id":"https:\/\/consorcioserrano.es\/#\/schema\/person\/349ec1d93548782b3ecf3331d50e0535"},"description":"Consorcio Prosciutto Serrano Spagnolo: garanzia del miglior Prosciutto Serrano - 100% prosciutti spagnoli - Prosciutto crudo spagnolo selezionato a mano","breadcrumb":{"@id":"https:\/\/consorcioserrano.es\/it\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/consorcioserrano.es\/it\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/consorcioserrano.es\/it\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\/#primaryimage","url":"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2021\/12\/camion_contenedores.jpg","contentUrl":"https:\/\/consorcioserrano.es\/wp-content\/uploads\/2021\/12\/camion_contenedores.jpg","width":612,"height":406,"caption":"Exportacion Jam\u00f3n Serrano"},{"@type":"BreadcrumbList","@id":"https:\/\/consorcioserrano.es\/it\/le-esportazioni-di-prosciutto-e-prosciuttini-stagionati-crescono-del-1417-fino-al-terzo-trimestre-del-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/consorcioserrano.es\/it\/inicio\/"},{"@type":"ListItem","position":2,"name":"Le esportazioni di prosciutto e prosciuttini stagionati crescono del 14,17% fino al terzo trimestre del 2021"}]},{"@type":"WebSite","@id":"https:\/\/consorcioserrano.es\/#website","url":"https:\/\/consorcioserrano.es\/","name":"Consorcio del Jam\u00f3n Serrano Espa\u00f1ol","description":"Consorcio Prosciutto Serrano Spagnolo: garanzia del miglior Prosciutto Serrano - 100% prosciutti spagnoli - Prosciutto crudo spagnolo selezionato a mano","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/consorcioserrano.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/consorcioserrano.es\/#\/schema\/person\/349ec1d93548782b3ecf3331d50e0535","name":"eMutation"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/posts\/14573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/comments?post=14573"}],"version-history":[{"count":1,"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/posts\/14573\/revisions"}],"predecessor-version":[{"id":14574,"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/posts\/14573\/revisions\/14574"}],"wp:attachment":[{"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/media?parent=14573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/categories?post=14573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consorcioserrano.es\/it\/wp-json\/wp\/v2\/tags?post=14573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}